{"id":3431,"date":"2020-07-23T20:02:11","date_gmt":"2020-07-23T20:02:11","guid":{"rendered":"http:\/\/blogs.es.amnesty.org\/madrid\/?p=3431"},"modified":"2020-07-23T20:02:12","modified_gmt":"2020-07-23T20:02:12","slug":"irak-protestas-y-represion-detenidas-por-el-covid-19","status":"publish","type":"post","link":"https:\/\/blogs.es.amnesty.org\/madrid\/2020\/07\/23\/irak-protestas-y-represion-detenidas-por-el-covid-19\/","title":{"rendered":"Irak: protestas (y represi\u00f3n) detenidas por el COVID-19"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Autor: Juan Bautista Cartes, Equipo Medio Oriente y Norte de \u00c1frica (MENA) de Amnist\u00eda Internacional Madrid<\/h3>\n\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">Tras las entradas dedicadas a <a href=\"https:\/\/blogs.es.amnesty.org\/madrid\/2020\/05\/09\/profesion-de-riesgo-escritor-en-los-territorios-ocupados-palestinos\/\">Palestina<\/a>, <a href=\"https:\/\/blogs.es.amnesty.org\/madrid\/2020\/05\/23\/welcome-to-iran-un-pueblo-silenciado\/\">Ir\u00e1n<\/a> y <a href=\"https:\/\/blogs.es.amnesty.org\/madrid\/2020\/07\/16\/marruecos-y-sahara-occidental-silencio-se-vigila\/\">S\u00e1hara Occidental<\/a>, concluimos nuestra serie sobre libertad de expresi\u00f3n en la Regi\u00f3n MENA centr\u00e1ndonos en el estado de Irak. En primer lugar, como informaci\u00f3n de contexto, hemos de tener en cuenta que <strong>a pesar de que la campa\u00f1a militar contra el Daesh se dio por concluida a finales de 2017<\/strong>, tanto el Gobierno central iraqu\u00ed como el Gobierno de la regi\u00f3n del Kurdist\u00e1n siguen desarrollando operaciones militares a peque\u00f1a escala contra c\u00e9lulas supervivientes del grupo terrorista. Por su parte, aunque los desplazados internos comienzan a regresar a sus lugares de origen, <strong>el ritmo de reconstrucci\u00f3n es muy lento y la ayuda al desarrollo en 2019 mengu\u00f3 respecto a a\u00f1os anteriores<\/strong>. Adem\u00e1s, ese mismo a\u00f1o, el Kurdist\u00e1n iraqu\u00ed ha sido el destino de m\u00e1s de 17.000 personas que hu\u00edan de las operaciones militares turcas en el noroeste de Siria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Centr\u00e1ndonos en la libertad de expresi\u00f3n, en octubre de 2019 se expandieron las protestas multitudinarias por todo Irak aclamando la <strong>mejora de los servicios p\u00fablicos, las condiciones de empleo y el fin de la corrupci\u00f3n<\/strong>. Si bien tales protestas lograron la dimisi\u00f3n del primer ministro Adil Abdul Mahdi, <a href=\"https:\/\/www.es.amnesty.org\/en-que-estamos\/noticias\/noticia\/articulo\/irak-reconstruccion-3d-muestra-que-las-fuerzas-de-seguridad-mataron-deliberadamente-a-manifestantes\/\">Amnist\u00eda Internacional ha denunciado el <strong>uso de fuerza excesiva contra los manifestantes por parte de los cuerpos de seguridad<\/strong><\/a>, as\u00ed como detenciones arbitrarias e intimidaci\u00f3n contra activistas o profesionales del derecho que representaban a los propios manifestantes. Igualmente, las autoridades establecieron toques de queda y <strong>bloquearon el acceso a internet <\/strong>en todo el pa\u00eds. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras la expansi\u00f3n del COVID-19, y decretarse, por ende, un confinamiento parcial de la poblaci\u00f3n, <strong>las protestas se redujeron en gran medida<\/strong>. No obstante, tras la elecci\u00f3n de un nuevo primer ministro, Mustafa al Kadhim,\u00a0estas han vuelto ha resurgir. Al respecto, <strong><a href=\"https:\/\/www.es.amnesty.org\/en-que-estamos\/noticias\/noticia\/articulo\/irak-el-nuevo-gobierno-debe-situar-los-derechos-humanos-en-el-centro-de-su-agenda\/\">Amnist\u00eda Internacional ha dirigido una carta abierta al nuevo dirigent<\/a><\/strong>e inst\u00e1ndole a garantizar los derechos humanos y a que estos ocupen un lugar central en la nueva agenda. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1044\" height=\"696\" src=\"https:\/\/blogs.es.amnesty.org\/files\/uploads\/sites\/4\/2020\/07\/23cb0082-a0c2-4b42-95ba-6ffb0a3ba284-1044x696.jpeg\" alt=\"\" class=\"wp-image-3433\" srcset=\"https:\/\/blogs.es.amnesty.org\/files\/uploads\/sites\/4\/2020\/07\/23cb0082-a0c2-4b42-95ba-6ffb0a3ba284-1044x696.jpeg 1044w, https:\/\/blogs.es.amnesty.org\/files\/uploads\/sites\/4\/2020\/07\/23cb0082-a0c2-4b42-95ba-6ffb0a3ba284-770x513.jpeg 770w, https:\/\/blogs.es.amnesty.org\/files\/uploads\/sites\/4\/2020\/07\/23cb0082-a0c2-4b42-95ba-6ffb0a3ba284-768x512.jpeg 768w, https:\/\/blogs.es.amnesty.org\/files\/uploads\/sites\/4\/2020\/07\/23cb0082-a0c2-4b42-95ba-6ffb0a3ba284-1536x1023.jpeg 1536w, https:\/\/blogs.es.amnesty.org\/files\/uploads\/sites\/4\/2020\/07\/23cb0082-a0c2-4b42-95ba-6ffb0a3ba284.jpeg 1600w\" sizes=\"auto, (max-width: 1044px) 100vw, 1044px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Como en las entradas anteriores concluimos esta p\u00edldora informativa con un reflexivo poema, en este caso, del iraqu\u00ed Abdul Hadi Sadoun. <\/p>\n\n\n\n<pre class=\"wp-block-verse has-text-align-center\"><strong>La ciudad<\/strong><br \/> Y la ciudad ahora,<br \/> una l\u00ednea torcida en mis manos<br \/> un callejero de desilusiones.<br \/> Desde esta puerta salgo a recibir al d\u00eda<br \/> y desde la misma despido los atardeceres<br \/> que se empapan en su fiesta de \u00e1mbar.<br \/> Ante esta piedra<br \/> almaceno mi aliento para otra novillada.<br \/> Es un d\u00eda confuso y desacorde<br \/> planifica mis destinos en la cesta de la nada.<br \/> Aqu\u00ed mis pasos<br \/> estampan sus eternos laberintos.<br \/> El atardecer gris <br \/> espera<br \/> la fruta que cosecha mi ma\u00f1ana.<br \/> Aqu\u00ed mis nubes merman, <br \/> sombra de tentativas crudas.<br \/> Nos une <br \/>el miedo, no el amor, querida<br \/> por eso nos abrazamos todo el rato.<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Tras hacer frente a amenazas como el Daesh, una ola de protestas ciudadanas se ha expandido por Irak exigiendo mejoras en las condiciones de vida, as\u00ed como el fin de la corrupci\u00f3n. El COVID-19 las detuvo, pero han vuelto a resurgir. <\/p>\n","protected":false},"author":29,"featured_media":3432,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[34],"tags":[147,148,159,107,157],"class_list":["post-3431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-libertad-de-expresion","tag-coronavirus","tag-covid-19","tag-irak","tag-libertad-de-expresion","tag-mena"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Irak: protestas (y represi\u00f3n) detenidas por el COVID-19 - Madrid<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.es.amnesty.org\/madrid\/2020\/07\/23\/irak-protestas-y-represion-detenidas-por-el-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Irak: protestas (y represi\u00f3n) detenidas por el COVID-19 - Madrid\" \/>\n<meta property=\"og:description\" content=\"Tras hacer frente a amenazas como el Daesh, una ola de protestas ciudadanas se ha expandido por Irak exigiendo mejoras en las condiciones de vida, as\u00ed como el fin de la corrupci\u00f3n. El COVID-19 las detuvo, pero han vuelto a resurgir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.es.amnesty.org\/madrid\/2020\/07\/23\/irak-protestas-y-represion-detenidas-por-el-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Madrid\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-23T20:02:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-23T20:02:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.es.amnesty.org\/files\/uploads\/sites\/4\/2020\/07\/da94ee05-98bb-427b-906f-dd934329e26d.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipo MENA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo MENA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/2020\\\/07\\\/23\\\/irak-protestas-y-represion-detenidas-por-el-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/2020\\\/07\\\/23\\\/irak-protestas-y-represion-detenidas-por-el-covid-19\\\/\"},\"author\":{\"name\":\"Equipo MENA\",\"@id\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/#\\\/schema\\\/person\\\/6fc4906bb5b8ef242e98d5c560216f66\"},\"headline\":\"Irak: protestas (y represi\u00f3n) detenidas por el COVID-19\",\"datePublished\":\"2020-07-23T20:02:11+00:00\",\"dateModified\":\"2020-07-23T20:02:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/2020\\\/07\\\/23\\\/irak-protestas-y-represion-detenidas-por-el-covid-19\\\/\"},\"wordCount\":394,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/2020\\\/07\\\/23\\\/irak-protestas-y-represion-detenidas-por-el-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/files\\\/uploads\\\/sites\\\/4\\\/2020\\\/07\\\/da94ee05-98bb-427b-906f-dd934329e26d.jpeg\",\"keywords\":[\"Coronavirus\",\"COVID-19\",\"Irak\",\"Libertad de expresi\u00f3n\",\"MENA\"],\"articleSection\":[\"Libertad de expresi\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/2020\\\/07\\\/23\\\/irak-protestas-y-represion-detenidas-por-el-covid-19\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/2020\\\/07\\\/23\\\/irak-protestas-y-represion-detenidas-por-el-covid-19\\\/\",\"url\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/2020\\\/07\\\/23\\\/irak-protestas-y-represion-detenidas-por-el-covid-19\\\/\",\"name\":\"Irak: protestas (y represi\u00f3n) detenidas por el COVID-19 - Madrid\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/2020\\\/07\\\/23\\\/irak-protestas-y-represion-detenidas-por-el-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/2020\\\/07\\\/23\\\/irak-protestas-y-represion-detenidas-por-el-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/files\\\/uploads\\\/sites\\\/4\\\/2020\\\/07\\\/da94ee05-98bb-427b-906f-dd934329e26d.jpeg\",\"datePublished\":\"2020-07-23T20:02:11+00:00\",\"dateModified\":\"2020-07-23T20:02:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/#\\\/schema\\\/person\\\/6fc4906bb5b8ef242e98d5c560216f66\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/2020\\\/07\\\/23\\\/irak-protestas-y-represion-detenidas-por-el-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/2020\\\/07\\\/23\\\/irak-protestas-y-represion-detenidas-por-el-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/2020\\\/07\\\/23\\\/irak-protestas-y-represion-detenidas-por-el-covid-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/files\\\/uploads\\\/sites\\\/4\\\/2020\\\/07\\\/da94ee05-98bb-427b-906f-dd934329e26d.jpeg\",\"contentUrl\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/files\\\/uploads\\\/sites\\\/4\\\/2020\\\/07\\\/da94ee05-98bb-427b-906f-dd934329e26d.jpeg\",\"width\":1600,\"height\":1066,\"caption\":\"El poeta Abdul Hadi Sadoun durante la lectura de poemas sobre la situaci\u00f3n de Irak organizada por Amnist\u00eda Internacional Madrid\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/2020\\\/07\\\/23\\\/irak-protestas-y-represion-detenidas-por-el-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Irak: protestas (y represi\u00f3n) detenidas por el COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/#website\",\"url\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/\",\"name\":\"Madrid\",\"description\":\"Blog de Amnist\u00eda Internacional Madrid\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/#\\\/schema\\\/person\\\/6fc4906bb5b8ef242e98d5c560216f66\",\"name\":\"Equipo MENA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/937550929da4a63724cd4b283ace9aae2337649d9b3c60c763feb6f453041fee?s=96&d=https%3A%2F%2Fblogs.es.amnesty.org%2Ffiles%2Fuploads%2F2019%2F02%2Fanmistia-gravatar.jpg&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/937550929da4a63724cd4b283ace9aae2337649d9b3c60c763feb6f453041fee?s=96&d=https%3A%2F%2Fblogs.es.amnesty.org%2Ffiles%2Fuploads%2F2019%2F02%2Fanmistia-gravatar.jpg&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/937550929da4a63724cd4b283ace9aae2337649d9b3c60c763feb6f453041fee?s=96&d=https%3A%2F%2Fblogs.es.amnesty.org%2Ffiles%2Fuploads%2F2019%2F02%2Fanmistia-gravatar.jpg&r=g\",\"caption\":\"Equipo MENA\"},\"url\":\"https:\\\/\\\/blogs.es.amnesty.org\\\/madrid\\\/autor\\\/mena\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Irak: protestas (y represi\u00f3n) detenidas por el COVID-19 - Madrid","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.es.amnesty.org\/madrid\/2020\/07\/23\/irak-protestas-y-represion-detenidas-por-el-covid-19\/","og_locale":"es_ES","og_type":"article","og_title":"Irak: protestas (y represi\u00f3n) detenidas por el COVID-19 - Madrid","og_description":"Tras hacer frente a amenazas como el Daesh, una ola de protestas ciudadanas se ha expandido por Irak exigiendo mejoras en las condiciones de vida, as\u00ed como el fin de la corrupci\u00f3n. El COVID-19 las detuvo, pero han vuelto a resurgir.","og_url":"https:\/\/blogs.es.amnesty.org\/madrid\/2020\/07\/23\/irak-protestas-y-represion-detenidas-por-el-covid-19\/","og_site_name":"Madrid","article_published_time":"2020-07-23T20:02:11+00:00","article_modified_time":"2020-07-23T20:02:12+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/blogs.es.amnesty.org\/files\/uploads\/sites\/4\/2020\/07\/da94ee05-98bb-427b-906f-dd934329e26d.jpeg","type":"image\/jpeg"}],"author":"Equipo MENA","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Equipo MENA","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.es.amnesty.org\/madrid\/2020\/07\/23\/irak-protestas-y-represion-detenidas-por-el-covid-19\/#article","isPartOf":{"@id":"https:\/\/blogs.es.amnesty.org\/madrid\/2020\/07\/23\/irak-protestas-y-represion-detenidas-por-el-covid-19\/"},"author":{"name":"Equipo MENA","@id":"https:\/\/blogs.es.amnesty.org\/madrid\/#\/schema\/person\/6fc4906bb5b8ef242e98d5c560216f66"},"headline":"Irak: protestas (y represi\u00f3n) detenidas por el COVID-19","datePublished":"2020-07-23T20:02:11+00:00","dateModified":"2020-07-23T20:02:12+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.es.amnesty.org\/madrid\/2020\/07\/23\/irak-protestas-y-represion-detenidas-por-el-covid-19\/"},"wordCount":394,"commentCount":1,"image":{"@id":"https:\/\/blogs.es.amnesty.org\/madrid\/2020\/07\/23\/irak-protestas-y-represion-detenidas-por-el-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.es.amnesty.org\/files\/uploads\/sites\/4\/2020\/07\/da94ee05-98bb-427b-906f-dd934329e26d.jpeg","keywords":["Coronavirus","COVID-19","Irak","Libertad de expresi\u00f3n","MENA"],"articleSection":["Libertad de expresi\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.es.amnesty.org\/madrid\/2020\/07\/23\/irak-protestas-y-represion-detenidas-por-el-covid-19\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.es.amnesty.org\/madrid\/2020\/07\/23\/irak-protestas-y-represion-detenidas-por-el-covid-19\/","url":"https:\/\/blogs.es.amnesty.org\/madrid\/2020\/07\/23\/irak-protestas-y-represion-detenidas-por-el-covid-19\/","name":"Irak: protestas (y represi\u00f3n) detenidas por el COVID-19 - Madrid","isPartOf":{"@id":"https:\/\/blogs.es.amnesty.org\/madrid\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.es.amnesty.org\/madrid\/2020\/07\/23\/irak-protestas-y-represion-detenidas-por-el-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/blogs.es.amnesty.org\/madrid\/2020\/07\/23\/irak-protestas-y-represion-detenidas-por-el-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.es.amnesty.org\/files\/uploads\/sites\/4\/2020\/07\/da94ee05-98bb-427b-906f-dd934329e26d.jpeg","datePublished":"2020-07-23T20:02:11+00:00","dateModified":"2020-07-23T20:02:12+00:00","author":{"@id":"https:\/\/blogs.es.amnesty.org\/madrid\/#\/schema\/person\/6fc4906bb5b8ef242e98d5c560216f66"},"breadcrumb":{"@id":"https:\/\/blogs.es.amnesty.org\/madrid\/2020\/07\/23\/irak-protestas-y-represion-detenidas-por-el-covid-19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.es.amnesty.org\/madrid\/2020\/07\/23\/irak-protestas-y-represion-detenidas-por-el-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.es.amnesty.org\/madrid\/2020\/07\/23\/irak-protestas-y-represion-detenidas-por-el-covid-19\/#primaryimage","url":"https:\/\/blogs.es.amnesty.org\/files\/uploads\/sites\/4\/2020\/07\/da94ee05-98bb-427b-906f-dd934329e26d.jpeg","contentUrl":"https:\/\/blogs.es.amnesty.org\/files\/uploads\/sites\/4\/2020\/07\/da94ee05-98bb-427b-906f-dd934329e26d.jpeg","width":1600,"height":1066,"caption":"El poeta Abdul Hadi Sadoun durante la lectura de poemas sobre la situaci\u00f3n de Irak organizada por Amnist\u00eda Internacional Madrid"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.es.amnesty.org\/madrid\/2020\/07\/23\/irak-protestas-y-represion-detenidas-por-el-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogs.es.amnesty.org\/madrid\/"},{"@type":"ListItem","position":2,"name":"Irak: protestas (y represi\u00f3n) detenidas por el COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/blogs.es.amnesty.org\/madrid\/#website","url":"https:\/\/blogs.es.amnesty.org\/madrid\/","name":"Madrid","description":"Blog de Amnist\u00eda Internacional Madrid","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.es.amnesty.org\/madrid\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/blogs.es.amnesty.org\/madrid\/#\/schema\/person\/6fc4906bb5b8ef242e98d5c560216f66","name":"Equipo MENA","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/937550929da4a63724cd4b283ace9aae2337649d9b3c60c763feb6f453041fee?s=96&d=https%3A%2F%2Fblogs.es.amnesty.org%2Ffiles%2Fuploads%2F2019%2F02%2Fanmistia-gravatar.jpg&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/937550929da4a63724cd4b283ace9aae2337649d9b3c60c763feb6f453041fee?s=96&d=https%3A%2F%2Fblogs.es.amnesty.org%2Ffiles%2Fuploads%2F2019%2F02%2Fanmistia-gravatar.jpg&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/937550929da4a63724cd4b283ace9aae2337649d9b3c60c763feb6f453041fee?s=96&d=https%3A%2F%2Fblogs.es.amnesty.org%2Ffiles%2Fuploads%2F2019%2F02%2Fanmistia-gravatar.jpg&r=g","caption":"Equipo MENA"},"url":"https:\/\/blogs.es.amnesty.org\/madrid\/autor\/mena\/"}]}},"_links":{"self":[{"href":"https:\/\/blogs.es.amnesty.org\/madrid\/wp-json\/wp\/v2\/posts\/3431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.es.amnesty.org\/madrid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.es.amnesty.org\/madrid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.es.amnesty.org\/madrid\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.es.amnesty.org\/madrid\/wp-json\/wp\/v2\/comments?post=3431"}],"version-history":[{"count":0,"href":"https:\/\/blogs.es.amnesty.org\/madrid\/wp-json\/wp\/v2\/posts\/3431\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.es.amnesty.org\/madrid\/wp-json\/wp\/v2\/media\/3432"}],"wp:attachment":[{"href":"https:\/\/blogs.es.amnesty.org\/madrid\/wp-json\/wp\/v2\/media?parent=3431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.es.amnesty.org\/madrid\/wp-json\/wp\/v2\/categories?post=3431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.es.amnesty.org\/madrid\/wp-json\/wp\/v2\/tags?post=3431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}